{"id":768,"date":"2020-07-08T21:29:53","date_gmt":"2020-07-08T21:29:53","guid":{"rendered":"http:\/\/carteame.es\/elcampanuen\/?page_id=768"},"modified":"2023-06-22T11:08:01","modified_gmt":"2023-06-22T11:08:01","slug":"revueltos","status":"publish","type":"page","link":"http:\/\/carteame.es\/elcampanuen\/revueltos\/","title":{"rendered":"SCRAMBLED EGGS"},"content":{"rendered":"<div class=\"accura-fmwp-food-menu\"> \r\n                \r\n \r\n             <div class=\"accura-fmwp-container\" id=\"template-six\">\r\n            <div class=\"accura-fmwp-border-box accura-fmwp-single-column\"> \r\n            <div class=\"accura-fmwp-clear replace\">\r\n            \r\n                         \r\n            <div class=\"accura-fmwp-hover-bg accura-fmwp-marbot30\">\r\n            \r\n            <div class=\"accura-fmwp-clear   \">\r\n            \r\n            <div class=\"accura-fmwp-clear accura-fmwp-content-splider\">\r\n\t\t\t\t  \r\n           \r\n           <div class=\"clearfix\">\r\n           \r\n           <div class=\"accura-fmwp-marbot10 accura-fmwp-border-overflow accura-fmwp-content-splider\">\r\n           \r\n           <span class=\"accura-fmwp-content-right\">\r\n                \t <span class=\"accura-fmwp-regular-price\">13.00 \u20ac<\/span>            <\/span>\r\n           \r\n           \t\t<span class=\"accura-fmwp-content-left accura-fmwp-menu-items-title accura-fmwp-menu-border-bottom\">\r\n                \tScrambled eggs with wild mushrooms and prawns  \r\n                \r\n           <span>\r\n            \r\n              \r\n\r\n            <\/span>\r\n            \r\n                <\/span>\r\n  \r\n                \r\n           <\/div>\r\n          \r\n            <span class=\"    \">\r\n            \r\n  \r\n            <\/span>\r\n            \r\n\r\n                        <p class=\"accura-fmwp-item-description\"><\/p>\r\n                        \r\n            <\/div>\r\n            <\/div>\r\n            \r\n            <\/div>\r\n            <\/div>\r\n            \r\n                          \r\n            <div class=\"accura-fmwp-hover-bg accura-fmwp-marbot30\">\r\n            \r\n            <div class=\"accura-fmwp-clear   \">\r\n            \r\n            <div class=\"accura-fmwp-clear accura-fmwp-content-splider\">\r\n\t\t\t\t  \r\n           \r\n           <div class=\"clearfix\">\r\n           \r\n           <div class=\"accura-fmwp-marbot10 accura-fmwp-border-overflow accura-fmwp-content-splider\">\r\n           \r\n           <span class=\"accura-fmwp-content-right\">\r\n                \t <span class=\"accura-fmwp-regular-price\">12.00 \u20ac<\/span>            <\/span>\r\n           \r\n           \t\t<span class=\"accura-fmwp-content-left accura-fmwp-menu-items-title accura-fmwp-menu-border-bottom\">\r\n                \tScrambled eggs with elvers  \r\n                \r\n           <span>\r\n            \r\n              \r\n\r\n            <\/span>\r\n            \r\n                <\/span>\r\n  \r\n                \r\n           <\/div>\r\n          \r\n            <span class=\"    \">\r\n            \r\n  \r\n            <\/span>\r\n            \r\n\r\n                        <p class=\"accura-fmwp-item-description\"><\/p>\r\n                        \r\n            <\/div>\r\n            <\/div>\r\n            \r\n            <\/div>\r\n            <\/div>\r\n            \r\n                          \r\n            <\/div>\r\n            \r\n            <\/div>\r\n            <\/div>\r\n            \r\n            \r\n                          \r\n              \r\n<\/div>\n<p style=\"text-align: center;\">Muchas gracias por su visita.<br \/>\n10% IVA Incluido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchas gracias por su visita. 10% IVA Incluido.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/full-width-page.php","meta":{"footnotes":""},"class_list":["post-768","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/pages\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/comments?post=768"}],"version-history":[{"count":2,"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/pages\/768\/revisions"}],"predecessor-version":[{"id":999,"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/pages\/768\/revisions\/999"}],"wp:attachment":[{"href":"http:\/\/carteame.es\/elcampanuen\/wp-json\/wp\/v2\/media?parent=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}